{"id":57291,"date":"2024-06-17T10:12:27","date_gmt":"2024-06-17T08:12:27","guid":{"rendered":"https:\/\/www.batemo.com\/products\/batemo-cell-explorer\/klinge-c102f\/"},"modified":"2025-07-24T18:02:25","modified_gmt":"2025-07-24T16:02:25","slug":"byd-blade-c102f","status":"publish","type":"product","link":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/","title":{"rendered":"Blade C102F"},"content":{"rendered":"<table style=\"color:white\" border=\"5\" cellspacing=\"0\" cellpadding=\"2\">\n<colgroup>\n<col width=\"50%\">\n<col width=\"50%\"> <\/colgroup>\n<tbody>\n<tr>\n<td>Zellher\u00adkunft<\/td>\n<td style=\"text-align:right\">auf dem freien Markt gekauft<\/td>\n<\/tr>\n<tr>\n<td>Zellformat<\/td>\n<td style=\"text-align:right\">Prisma\u00adtisch<\/td>\n<\/tr>\n<tr>\n<td>Abmes\u00adsungen<\/td>\n<td style=\"text-align:right\">945 x 90,5 x 13,9&nbsp;mm<\/td>\n<\/tr>\n<tr>\n<td>Gewicht<\/td>\n<td style=\"text-align:right\">2,5363 kg<\/td>\n<\/tr>\n<tr>\n<td>Kapazit\u00e4t<br>\n<span class=\"collapseomatic noarrow\" id=\"id688258f4e7ab5\" title=\"definition\">defini\u00adtion<\/span><span id=\"swap-id688258f4e7ab5\" class=\"colomat-swap\">schlie\u00dfen<\/span>\n<div id=\"target-id688258f4e7ab5\" class=\"collapseomatic_content collapsible_orange\">\nDie Nennka\u00adpa\u00adzit\u00e4t stammt aus dem Daten\u00adblatt des Herstel\u00adlers, sofern verf\u00fcgbar. Wenn das Daten\u00adblatt nicht verf\u00fcgbar ist, wird die Nennka\u00adpa\u00adzit\u00e4t gesch\u00e4tzt. Batemo hat die C\/10-Kapazit\u00e4t gemessen, indem die Zelle bei einer Umgebungs\u00adtem\u00adpe\u00adratur von 25\u00b0C von 100% mit einem Konstant\u00adstrom von 13,80A (0,1C) bis zum Errei\u00adchen der Spannung von 2,0V entladen wurde. Die thermi\u00adsche Randbe\u00addin\u00adgung ist freie Konvektion.&nbsp;<\/div>\n<\/td>\n<td style=\"text-align:right\">\n<span style=\"font-size: 10px\">nominal<\/span>&nbsp;138,0 Ah<br>\n<span style=\"font-size: 10px\">C\/10<\/span>&nbsp;140,2 Ah<\/td>\n<\/tr>\n<tr>\n<td>Strom<br>\n<span class=\"collapseomatic noarrow\" id=\"id688258f4e7b58\" title=\"definition\">defini\u00adtion<\/span><span id=\"swap-id688258f4e7b58\" class=\"colomat-swap\">schlie\u00dfen<\/span>\n<div id=\"target-id688258f4e7b58\" class=\"collapseomatic_content collapsible_orange\">\nAlle Gr\u00f6\u00dfen sind Messergeb\u00adnisse aus dem Batemo-Batte\u00adrie\u00adlabor.<br> Der konti\u00adnu\u00adier\u00adliche Strom ist der h\u00f6chste Strom, der die Zelle vollst\u00e4ndig entl\u00e4dt, ohne sie zu \u00fcberhitzen. Dazu wird die Zelle von 100% Ladezu\u00adstand (SOC) bei einer Umgebungs\u00adtem\u00adpe\u00adratur von 25\u00b0C mit konstantem Strom bis zu einem Rest-Ladezu\u00adstand von 10% und entweder der unteren Spannungs\u00adgrenze von 2,0V oder 90% der maximalen Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur (50\u00b0C) entladen.<br> Der Spitzen\u00adstrom ist der Strom, den die Zelle 5 Minuten lang liefern kann. Dazu wird die Zelle von 100% SOC bei einer Umgebungs\u00adtem\u00adpe\u00adratur von 25\u00b0C mit konstantem Strom entladen, bis sie entweder die untere Spannungs\u00adgrenze von 2,0V oder die maximale Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur von 55\u00b0C nach 5 Minuten erreicht. F\u00fcr Zellen, die die maximale Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur errei\u00adchen, wird der gemes\u00adsene Strom direkt als Spitzen\u00adstrom \u00fcbernommen. F\u00fcr Zellen, die nach 5 Minuten nicht die maximale Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur errei\u00adchen, weil sie zuerst die untere Spannungs\u00adgrenze errei\u00adchen, wird der gemes\u00adsene Strom mit einem Korrek\u00adtur\u00adfaktor multi\u00adpli\u00adziert, der den Strom absch\u00e4tzt, der die Zelle inner\u00adhalb von 5 Minuten auf die maximale Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur erhitzt h\u00e4tte.<br> Die thermi\u00adsche Randbe\u00addin\u00adgung ist freie Konvek\u00adtion. Diese Betriebs\u00adbe\u00addin\u00adgungen k\u00f6nnen au\u00dfer\u00adhalb der Spezi\u00adfi\u00adka\u00adtion des Zellher\u00adstel\u00adlers liegen.&nbsp;<\/div>\n<\/td>\n<td style=\"text-align:right\">\n<span style=\"font-size: 10px\">konti\u00adnu\u00adier\u00adlich<\/span>&nbsp;265 A<br>\n<span style=\"font-size: 10px\">Spitze<\/span>&nbsp;537 A<\/td>\n<\/tr>\n<tr>\n<td>Energie<br>\n<span class=\"collapseomatic noarrow\" id=\"id688258f4e7bd5\" title=\"definition\">defini\u00adtion<\/span><span id=\"swap-id688258f4e7bd5\" class=\"colomat-swap\">schlie\u00dfen<\/span>\n<div id=\"target-id688258f4e7bd5\" class=\"collapseomatic_content collapsible_orange\">\nBatemo hat die C\/10-Energie gemessen, indem die Zelle bei einer Umgebungs\u00adtem\u00adpe\u00adratur von 25\u00b0C von 100% mit einem konstanten Strom von 13,80A (0,1C) bis zum Errei\u00adchen der Spannung von 2,0V entladen wurde. Die thermi\u00adsche Randbe\u00addin\u00adgung ist freie Konvektion.&nbsp;<\/div>\n<\/td>\n<td style=\"text-align:right\">\n<span style=\"font-size: 10px\">C\/10<\/span>&nbsp;453,9 Wh<\/td>\n<\/tr>\n<tr>\n<td>Leistung<br>\n<span class=\"collapseomatic noarrow\" id=\"id688258f4e7c4c\" title=\"definition\">defini\u00adtion<\/span><span id=\"swap-id688258f4e7c4c\" class=\"colomat-swap\">schlie\u00dfen<\/span>\n<div id=\"target-id688258f4e7c4c\" class=\"collapseomatic_content collapsible_orange\">\nAlle Angaben sind Messergeb\u00adnisse aus dem Batemo-Batte\u00adrie\u00adlabor.<br> Die konti\u00adnu\u00adier\u00adliche Leistung ist die h\u00f6chste Leistung, die die Zelle vollst\u00e4ndig entl\u00e4dt, ohne sie zu \u00fcberhitzen. Daher wird die Zelle von 100% Ladezu\u00adstand (SOC) bei einer Umgebungs\u00adtem\u00adpe\u00adratur von 25\u00b0C mit konstantem Strom bis zu einem Rest-Ladezu\u00adstand von 10% und entweder der unteren Spannungs\u00adgrenze von 2,0V oder 90% der maximalen Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur ( 50\u00b0C) entladen.<br> Die Spitzen\u00adleis\u00adtung ist die Leistung, die die Zelle 5 Minuten lang liefern kann. Daher wird die Zelle von 100% SOC bei einer Umgebungs\u00adtem\u00adpe\u00adratur von 25\u00b0C mit konstantem Strom entladen, bis sie entweder die untere Spannungs\u00adgrenze von 2,0V oder die maximale Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur von 55\u00b0C nach 5 Minuten erreicht. F\u00fcr Zellen, die die maximale Tempe\u00adra\u00adtur\u00adgrenze errei\u00adchen, wird die gemes\u00adsene Leistung direkt als Spitzen\u00adleis\u00adtung \u00fcbernommen. F\u00fcr Zellen, die nach 5 Minuten nicht die maximale Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur errei\u00adchen, weil sie zuerst die untere Spannungs\u00adgrenze errei\u00adchen, wird die gemes\u00adsene Leistung mit einem Korrek\u00adtur\u00adfaktor multi\u00adpli\u00adziert, der die Leistung absch\u00e4tzt, die die Zelle inner\u00adhalb von 5 Minuten auf die maximale Oberfl\u00e4\u00adchen\u00adtem\u00adpe\u00adratur erhitzt h\u00e4tte.<br> Die thermi\u00adsche Randbe\u00addin\u00adgung ist freie Konvek\u00adtion. Diese Betriebs\u00adbe\u00addin\u00adgungen k\u00f6nnen au\u00dfer\u00adhalb der Spezi\u00adfi\u00adka\u00adtion des Zellher\u00adstel\u00adlers liegen.&nbsp;<\/div>\n<\/td>\n<td style=\"text-align:right\">\n<span style=\"font-size: 10px\">konti\u00adnu\u00adier\u00adlich<\/span>&nbsp;790 W<br>\n<span style=\"font-size: 10px\">Spitze<\/span>&nbsp;1,53 kW<\/td>\n<\/tr>\n<tr>\n<td>Energie\u00addichte<br>\n<span class=\"collapseomatic noarrow\" id=\"id688258f4e7cc3\" title=\"definition\">defini\u00adtion<\/span><span id=\"swap-id688258f4e7cc3\" class=\"colomat-swap\">schlie\u00dfen<\/span>\n<div id=\"target-id688258f4e7cc3\" class=\"collapseomatic_content collapsible_orange\">\nDie Energie\u00addichten ergeben sich aus der C\/10-Energie, dem Zellge\u00adwicht und dem Zellvolumen.&nbsp;<\/div>\n<\/td>\n<td style=\"text-align:right\">\n<span style=\"font-size: 10px\">gravi\u00adme\u00adtrisch<\/span>&nbsp;179 Wh\/kg<br>\n<span style=\"font-size: 10px\">volume\u00adtrisch<\/span>&nbsp;381 Wh\/l<\/td>\n<\/tr>\n<tr>\n<td>Leistungs\u00addichte<br>\n<span class=\"collapseomatic noarrow\" id=\"id688258f4e7d3a\" title=\"definition\">defini\u00adtion<\/span><span id=\"swap-id688258f4e7d3a\" class=\"colomat-swap\">schlie\u00dfen<\/span>\n<div id=\"target-id688258f4e7d3a\" class=\"collapseomatic_content collapsible_orange\">\nDie Leistungs\u00addichten ergeben sich aus der Spitzen\u00adleis\u00adtung, dem Zellge\u00adwicht und dem Zellvolumen.&nbsp;<\/div>\n<\/td>\n<td style=\"text-align:right\">\n<span style=\"font-size: 10px\">gravi\u00adme\u00adtrisch<\/span>&nbsp;604 W\/kg<br>\n<span style=\"font-size: 10px\">volume\u00adtrisch<\/span>&nbsp;1,29 kW\/l<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Erhalten Sie alles, was Sie f\u00fcr die Lithium-Ionen Batte\u00adrie\u00adzelle BYD Blade C102F ben\u00f6tigen: Umfang\u00adreiche Messdaten im gesamten Betriebs\u00adbe\u00adreich, ein hochpr\u00e4\u00adzises Batte\u00adrie\u00admo\u00addell mit globaler Validit\u00e4t sowie einen Tear-Down-Bericht mit detail\u00adlierten Infor\u00adma\u00adtionen zu Aufbau, Materia\u00adlien und Mikrostrukturen.<\/p>\n","protected":false},"featured_media":122355,"template":"","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","_links_to":"","_links_to_target":""},"product_brand":[],"product_cat":[2421],"product_tag":[2426,2427,2428,16692,16710,16704],"class_list":{"0":"post-57291","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-prismatic-de","7":"product_tag-batemo-cell-data-de","8":"product_tag-batemo-cell-model-de","9":"product_tag-batemo-cell-report-de","10":"product_tag-heavy-duty-de","11":"product_tag-rail-de","12":"product_tag-stationary-storage-de","13":"pa_capacity-1402-ah","14":"pa_continuous_current-26452-a","15":"pa_continuous_power-7904-w","16":"pa_dimensions-945-x-905-x-139-mm","17":"pa_energy-4539-wh","18":"pa_format-prismatic-de","19":"pa_gravimetric_capacity_density-553-ah-kg","20":"pa_gravimetric_current_density-2116-a-kg","21":"pa_gravimetric_energy_density-1789-wh-kg","22":"pa_gravimetric_power_density-604-w-kg","23":"pa_manufacturer-byd-de","24":"pa_nominal_capacity-138-ah","25":"pa_peak_current-53664-a","26":"pa_peak_power-15327-w","27":"pa_temperature_range-20-55-c","28":"pa_voltage_range-2-38-v","29":"pa_volumetric_capacity_density-1176-ah-l","30":"pa_volumetric_current_density-4502-a-l","31":"pa_volumetric_energy_density-381-wh-l","32":"pa_volumetric_power_density-1286-w-l","33":"pa_weight-25363-kg","34":"entry","35":"has-media","37":"first","38":"instock","39":"taxable","40":"shipping-taxable","41":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BYD Blade C102F Batteriedaten, Modell und Bericht<\/title>\n<meta name=\"description\" content=\"Erhalten Sie Messdaten, ein hochpr\u00e4zises Modell und einen detaillierten Bericht der Lithium-Ion Batteriezelle BYD Blade C102F.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blade C102F\" \/>\n<meta property=\"og:description\" content=\"Erhalten Sie Messdaten, ein hochpr\u00e4zises Modell und einen detaillierten Bericht der Lithium-Ion Batteriezelle BYD Blade C102F.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/\" \/>\n<meta property=\"og:site_name\" content=\"Batemo GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T16:02:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/\",\"url\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/\",\"name\":\"BYD Blade C102F Batteriedaten, Modell und Bericht\",\"isPartOf\":{\"@id\":\"https:\/\/batemo.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png\",\"datePublished\":\"2024-06-17T08:12:27+00:00\",\"dateModified\":\"2025-07-24T16:02:25+00:00\",\"description\":\"Erhalten Sie Messdaten, ein hochpr\u00e4zises Modell und einen detaillierten Bericht der Lithium-Ion Batteriezelle BYD Blade C102F.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#primaryimage\",\"url\":\"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png\",\"contentUrl\":\"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Batemo\",\"item\":\"https:\/\/www.batemo.com\/de\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Batemo Cell Explorer\",\"item\":\"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blade C102F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/batemo.com\/#website\",\"url\":\"https:\/\/batemo.com\/\",\"name\":\"Batemo GmbH\",\"description\":\"Understanding Batteries\",\"publisher\":{\"@id\":\"https:\/\/batemo.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/batemo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/batemo.com\/#organization\",\"name\":\"Batemo GmbH\",\"url\":\"https:\/\/batemo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/batemo.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/batemo.com\/wp-content\/uploads\/Batemo-Logo.png\",\"contentUrl\":\"https:\/\/batemo.com\/wp-content\/uploads\/Batemo-Logo.png\",\"width\":499,\"height\":127,\"caption\":\"Batemo GmbH\"},\"image\":{\"@id\":\"https:\/\/batemo.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/batemo\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BYD Blade C102F Batteriedaten, Modell und Bericht","description":"Erhalten Sie Messdaten, ein hochpr\u00e4zises Modell und einen detaillierten Bericht der Lithium-Ion Batteriezelle BYD Blade C102F.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/","og_locale":"de_DE","og_type":"article","og_title":"Blade C102F","og_description":"Erhalten Sie Messdaten, ein hochpr\u00e4zises Modell und einen detaillierten Bericht der Lithium-Ion Batteriezelle BYD Blade C102F.","og_url":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/","og_site_name":"Batemo GmbH","article_modified_time":"2025-07-24T16:02:25+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/","url":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/","name":"BYD Blade C102F Batteriedaten, Modell und Bericht","isPartOf":{"@id":"https:\/\/batemo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#primaryimage"},"image":{"@id":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#primaryimage"},"thumbnailUrl":"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png","datePublished":"2024-06-17T08:12:27+00:00","dateModified":"2025-07-24T16:02:25+00:00","description":"Erhalten Sie Messdaten, ein hochpr\u00e4zises Modell und einen detaillierten Bericht der Lithium-Ion Batteriezelle BYD Blade C102F.","breadcrumb":{"@id":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#primaryimage","url":"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png","contentUrl":"https:\/\/www.batemo.com\/wp-content\/uploads\/BYD_BladeC102F_virtual.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/byd-blade-c102f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Batemo","item":"https:\/\/www.batemo.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Batemo Cell Explorer","item":"https:\/\/www.batemo.com\/de\/products\/batemo-cell-explorer\/"},{"@type":"ListItem","position":3,"name":"Blade C102F"}]},{"@type":"WebSite","@id":"https:\/\/batemo.com\/#website","url":"https:\/\/batemo.com\/","name":"Batemo GmbH","description":"Understanding Batteries","publisher":{"@id":"https:\/\/batemo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/batemo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/batemo.com\/#organization","name":"Batemo GmbH","url":"https:\/\/batemo.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/batemo.com\/#\/schema\/logo\/image\/","url":"https:\/\/batemo.com\/wp-content\/uploads\/Batemo-Logo.png","contentUrl":"https:\/\/batemo.com\/wp-content\/uploads\/Batemo-Logo.png","width":499,"height":127,"caption":"Batemo GmbH"},"image":{"@id":"https:\/\/batemo.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/batemo\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/product\/57291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/product\/57291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/media\/122355"}],"wp:attachment":[{"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/media?parent=57291"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/product_brand?post=57291"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/product_cat?post=57291"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.batemo.com\/de\/wp-json\/wp\/v2\/product_tag?post=57291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}